{"id":2069,"date":"2019-04-05T08:57:26","date_gmt":"2019-04-05T08:57:26","guid":{"rendered":"https:\/\/globusetlocus.com\/chi-siamo\/"},"modified":"2026-01-13T11:01:57","modified_gmt":"2026-01-13T10:01:57","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.globusetlocus.org\/en\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row bg_check=&#8221;row-background-dark&#8221; dfd_bg_style=&#8221;image&#8221; dfd_bg_image_new=&#8221;1537&#8243; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#000000&#8243; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;50&#8243;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"160\" data-normal_resolution=\"1024\" data-normal_size=\"140\" data-tablet_resolution=\"800\" data-tablet_size=\"120\" data-mobile_resolution=\"480\" data-mobile_size=\"100\" style=\"height: 160px;\"><\/div><div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_02 cr-animate-gen dfd-heading-6a97d04924403 dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d04924403\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><h1 class=\"widget-title dfd-title \" style=\"\">About us<\/h1><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d04924403.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}@media (max-width: 799px){.dfd-heading-6a97d04924403 .dfd-title{font-size: 50px !important;line-height: 50px !important;}}@media (max-width: 799px){.dfd-heading-6a97d04924403 .dfd-sub-title{letter-spacing: 2px !important;}}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"160\" data-normal_resolution=\"1024\" data-normal_size=\"140\" data-tablet_resolution=\"800\" data-tablet_size=\"120\" data-mobile_resolution=\"480\" data-mobile_size=\"100\" style=\"height: 160px;\"><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row dfd_bg_style=&#8221;image&#8221; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#ffffff&#8221; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;85&#8243; disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"80\" data-normal_resolution=\"1024\" data-normal_size=\"80\" data-tablet_resolution=\"800\" data-tablet_size=\"60\" data-mobile_resolution=\"480\" data-mobile_size=\"40\" style=\"height: 80px;\"><\/div><div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_02 cr-animate-gen dfd-heading-6a97d04924983 dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d04924983\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><div class=\"widget-sub-title dfd-sub-title subtitle\" style=\"letter-spacing: 0px; \">L'associazione Globus et Locus nasce nel 1997 con l\u2019obiettivo di aiutare le classi dirigenti ad affrontare le sfide della glocalizzazione con una cultura politica nuova e un sistema di valori aggiornato alla realt\u00e0 glocal.<\/div><h1 class=\"widget-title dfd-title \" style=\"\">Chi Siamo<\/h1><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d04924983 .dfd-heading-module .widget-sub-title {margin-bottom:20px;}.dfd-heading-6a97d04924983.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}@media (max-width: 799px){.dfd-heading-6a97d04924983 .dfd-title{font-size: 50px !important;line-height: 50px !important;}}@media (max-width: 799px){.dfd-heading-6a97d04924983 .dfd-sub-title{letter-spacing: 2px !important;}}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"40\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"40\" data-mobile_resolution=\"480\" data-mobile_size=\"40\" style=\"height: 40px;\"><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"40\" data-mobile_resolution=\"480\" data-mobile_size=\"30\" style=\"height: 50px;\"><\/div>[vc_single_image image=&#8221;1453&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1645095126694{padding-right: 25px !important;padding-left: 25px !important;}&#8221;][\/vc_column][\/vc_row][vc_row dfd_enable_overlay=&#8221;&#8221; force_equal_height_columns=&#8221;main_row&#8221; mobile_destroy_equal_heights_resolution=&#8221;799&#8243; dfd_row_config=&#8221;full_width_content&#8221; el_class=&#8221;bg-position-class&#8221; mobile_destroy_equal_heights=&#8221;yes&#8221; css=&#8221;.vc_custom_1644858765798{padding-right: 40px !important;padding-left: 40px !important;}&#8221;][vc_column dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_mobile:0|padding_right_mobile:20&#8243; el_class=&#8221;dfd_col-tablet-12&#8243; offset=&#8221;vc_col-lg-6 vc_col-md-6 vc_hidden-sm vc_col-xs-12 vc_hidden-xs&#8221; css=&#8221;.vc_custom_1645095097890{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"30\" data-normal_resolution=\"1024\" data-normal_size=\"30\" data-tablet_resolution=\"800\" data-tablet_size=\"30\" data-mobile_resolution=\"480\" data-mobile_size=\"30\" style=\"height: 30px;\"><\/div>[vc_column_text item_animation=&#8221;transition.slideUpBigIn&#8221;]<\/p>\n<p style=\"font-weight: 400;\">The Association Globus et Locus was established in 1997 by the Chamber of Commerce of Milan and the Universit\u00e0 Cattolica del Sacro Cuore (founding members) with the goal of supporting the ruling class in its efforts to deal with the challenges of glocalisation by providing both a new political culture and a system of values in line with glocal experience.<\/p>\n<p style=\"font-weight: 400;\">From its inception, Globus et Locus has aimed at developing political behaviour that is in tune with the epochal change produced by glocalisation.<\/p>\n<p style=\"font-weight: 400;\">The awareness that processes of globalisation change the shape of traditional political-economic systems is the fundamental concept inspiring Globus et Locus\u2019 thought and action. The changing organisational paradigms of the world has placed societies at the forefront of a series of important economic, institutional, and cultural transformations.<\/p>\n<p style=\"font-weight: 400;\">Over the years, the association has worked to propose projects and carry out research on glocal phenomena by both dialoguing in close synergy with its members and working together with other institutions and centres of study from all over the world.<\/p>\n<p>[\/vc_column_text]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"40\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"40\" data-mobile_resolution=\"480\" data-mobile_size=\"0\" style=\"height: 40px;\"><\/div>[vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div id=\"dfd-button-6a97d04925146\" class=\"dfd-button-module-wrap dfd-button-6a97d04925146\"><div class=\"dfd-button-module  style_1 text-left dfd-horizontal dfd-top-to-bottom dfd-button-icon-left dfd-button-icon-hover-simple\" ><a href=\"https:\/\/globusetlocus.org\/en\/governing-bodies\/\" title=\"Governing Bodies\" class=\"dfd-button-link\"><span class=\"dfd-button-inner-cover\"><span class=\"dfd-button-text-main\">Governing Bodies<\/span><\/span><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {$(\"head\").append(\"<style>#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {color: #ffffff}#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-border-decoration,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {background: #ea373f;border-style:none;border-width:1px;border-radius:2px;border-color:#1b1b1b;}#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {color: #ffffff;}#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-border-decoration,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover .dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {background: #ea373f;border-style:none;border-width:1px;border-radius:2px;border-color:#c39f76;}#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,#dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97d04925146.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before {border-style:none;border-width:1px;border-radius:2px;border-color:#c39f76;}<\/style>\")\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"40\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"40\" data-mobile_resolution=\"480\" data-mobile_size=\"0\" style=\"height: 40px;\"><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div id=\"dfd-button-6a97d0492541f\" class=\"dfd-button-module-wrap dfd-button-6a97d0492541f\"><div class=\"dfd-button-module  style_1 text-left dfd-horizontal dfd-top-to-bottom dfd-button-icon-left dfd-button-icon-hover-simple\" ><a href=\"https:\/\/globusetlocus.org\/statuto\/\" class=\"dfd-button-link\"><span class=\"dfd-button-inner-cover\"><span class=\"dfd-button-text-main\">Statute<\/span><\/span><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {$(\"head\").append(\"<style>#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {color: #ffffff}#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-border-decoration,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {background: #ea373f;border-style:none;border-width:1px;border-radius:2px;border-color:#1b1b1b;}#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {color: #ffffff;}#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-border-decoration,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover .dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {background: #ea373f;border-style:none;border-width:1px;border-radius:2px;border-color:#c39f76;}#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,#dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97d0492541f.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before {border-style:none;border-width:1px;border-radius:2px;border-color:#c39f76;}<\/style>\")\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"40\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"40\" data-mobile_resolution=\"480\" data-mobile_size=\"0\" style=\"height: 40px;\"><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div id=\"dfd-button-6a97d0492571c\" class=\"dfd-button-module-wrap dfd-button-6a97d0492571c\"><div class=\"dfd-button-module  style_1 text-left dfd-horizontal dfd-top-to-bottom dfd-button-icon-left dfd-button-icon-hover-simple\" ><a href=\"https:\/\/globusetlocus.org\/amministrazione-trasparente\/\" class=\"dfd-button-link\"><span class=\"dfd-button-inner-cover\"><span class=\"dfd-button-text-main\">Amministrazione trasparente<\/span><\/span><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {$(\"head\").append(\"<style>#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {color: #ffffff}#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-border-decoration,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {background: #ea373f;border-style:none;border-width:1px;border-radius:2px;border-color:#1b1b1b;}#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {color: #ffffff;}#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-border-decoration,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover .dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {background: #ea373f;border-style:none;border-width:1px;border-radius:2px;border-color:#c39f76;}#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,#dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a97d0492571c.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before {border-style:none;border-width:1px;border-radius:2px;border-color:#c39f76;}<\/style>\")\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"50\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row][vc_row dfd_enable_overlay=&#8221;&#8221; force_equal_height_columns=&#8221;main_row&#8221; mobile_destroy_equal_heights_resolution=&#8221;799&#8243; dfd_row_config=&#8221;full_width_content&#8221; el_class=&#8221;bg-position-class&#8221; disable_element=&#8221;yes&#8221; mobile_destroy_equal_heights=&#8221;yes&#8221; css=&#8221;.vc_custom_1645785963185{padding-right: 40px !important;padding-left: 40px !important;background-color: #f9f9f9 !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; el_class=&#8221;custom-position-colum-class-2 dfd_col-tablet-12&#8243; offset=&#8221;vc_col-lg-6 vc_col-md-6 vc_col-xs-12&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_05 cr-animate-gen dfd-heading-6a97d04925976 dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d04925976\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><h3 class=\"widget-title dfd-title \" style=\"\">Il Presidente<\/h3><div class=\"widget-sub-title dfd-sub-title subtitle\" style=\"letter-spacing: 0px; \">Il glocalismo \u00e8 la conseguenza di una rivoluzione epocale, determinata dal fatto che la tecnologia, azzerando i concetti di spazio e di tempo, ha reso il mondo \u201cpiatto\u201d. In pratica, oggi non esistono luoghi che non siano in misura crescente attraversati da flussi globali di varia natura, e, per contro, non ci sono flussi globali che non siano in misura crescente declinati secondo le diverse e molteplici particolarit\u00e0 dei luoghi.<\/div><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d04925976.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}@media (max-width: 799px){.dfd-heading-6a97d04925976 .dfd-title{font-size: 32px !important;line-height: 32px !important;}}@media (max-width: 799px){.dfd-heading-6a97d04925976 .dfd-sub-title{letter-spacing: 2px !important;}}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[vc_column_text item_animation=&#8221;transition.slideUpBigIn&#8221;]Piero Bassetti, Presidente di Globus et Locus[\/vc_column_text]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"30\" data-normal_resolution=\"1024\" data-normal_size=\"30\" data-tablet_resolution=\"800\" data-tablet_size=\"30\" data-mobile_resolution=\"480\" data-mobile_size=\"30\" style=\"height: 30px;\"><\/div>[vc_column_text item_animation=&#8221;transition.slideUpBigIn&#8221;]<strong>Piero Bassetti\u00a0<\/strong>\u00e8 nato a Milano nel 1928. Si \u00e8 laureato in Economia e Commercio all\u2019Universit\u00e0 Bocconi di Milano, ha perfezionato gli studi come borsista Fulbright alla Cornell University (USA); come &#8220;Stringher&#8221; si \u00e8 specializzato successivamente in Scienze Economiche alla London School of Economics.<\/p>\n<p>Consigliere e Assessore del Comune di Milano dal 1956 al 1967. Primo Presidente della Regione Lombardia dal 1970 al 1974, deputato al Parlamento dal 1976 al 1982; dal 1982 al 1997 \u00e8 stato Presidente della Camera di Commercio Industria e Agricoltura di Milano nonch\u00e9 Presidente dell\u2019Unione delle Camere di Commercio Italiane (Unioncamere) dal 1983 al 1992. \u00c8 stato dal 1993 al novembre del 1999 Presidente dell&#8217;Associazione delle Camere di Commercio Italiane all\u2019estero (CCIE).[\/vc_column_text]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"40\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"40\" data-mobile_resolution=\"480\" data-mobile_size=\"0\" style=\"height: 40px;\"><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_mobile:0|padding_right_mobile:20&#8243; el_class=&#8221;dfd_col-tablet-12&#8243; offset=&#8221;vc_col-lg-6 vc_col-md-6 vc_col-xs-12&#8243; css=&#8221;.vc_custom_1644858844535{background-image: url(https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/piero-bassetti-copia-1.jpg?id=1442) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][\/vc_column][\/vc_row][vc_row dfd_row_config=&#8221;full_width_content&#8221; dfd_row_responsive_enable=&#8221;dfd-row-responsive-enable&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1645785970441{padding-right: 40px !important;padding-left: 40px !important;background-color: #f9f9f9 !important;}&#8221; responsive_styles=&#8221;padding_left_tablet:30|padding_right_tablet:30|padding_left_mobile:20|padding_right_mobile:20&#8243;][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"40\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"40\" data-mobile_resolution=\"480\" data-mobile_size=\"0\" style=\"height: 40px;\"><\/div>[vc_column_text item_animation=&#8221;transition.slideUpBigIn&#8221;]Attualmente \u00e8\u00a0<strong>Presidente di Globus et Locus\u00a0<\/strong>e della\u00a0<strong>Fondazione Giannino Bassetti\u00a0<\/strong>il cui scopo \u00e9 lo studio della \u201cresponsabilit\u00e0 nell\u2019innovazione\u201d. E&#8217; inoltre Editor in <a href=\"https:\/\/glocalismjournal.org\/\" target=\"_blank\" rel=\"noopener\">Chief di Glocalism Journal of culture, politcs and innovation<\/a>.<\/p>\n<p>Autore di numerosi saggi e studi di politica ed economia ha scritto\u00a0<em>Le Redini del Potere\u00a0<\/em>con Giacomo Corna Pellegrini (Editore Ceschina 1959),\u00a0<em>Occidente Scomodo\u00a0<\/em>(Editore Vallecchi 1978),\u00a0<em>L\u2019Italia si \u00e8 rotta<\/em>\u00a0(Editore Laterza 1996),\u00a0<em>Milanesi senza Milano<\/em>\u00a0(Editore Mursia 1999),\u00a0<strong><a href=\"http:\/\/www.globusetlocus.org\/Pubblicazioni\/Globali_E_Locali.kl\" target=\"_blank\" rel=\"noopener\"><em>Globali e Locali!<\/em><\/a><\/strong>\u00a0libro intervista di Sergio Roic a Piero Bassetti (Editore Giampiero Casagrande, 2002),\u00a0<strong><a href=\"http:\/\/www.globusetlocus.org\/?Sec=20296&amp;Inf=59661\" target=\"_blank\" rel=\"noopener\"><em>Italici<\/em>\u00a0<\/a><\/strong>\u00a0libro intervista di P. Accolla e N. d\u2019Aquino a Piero Bassetti (Editore Giampiero Casagrande, 2008),\u00a0<strong><a href=\"http:\/\/www.globusetlocus.org\/?Sec=20296&amp;Inf=48977\" target=\"_blank\" rel=\"noopener\"><em>Italic Lessons<\/em><\/a><\/strong>, saggio di N. d\u2019Aquino e Piero Bassetti (Editore Bordighera Press, 2010), <strong><em><a href=\"http:\/\/www.globusetlocus.org\/Pubblicazioni\/Svegliamoci-Italici-Manifesto-Per-Un-Futuro-Glocal.kl\">Svegliamoci Italici! Manifesto per un futuro glocal<\/a><\/em><\/strong>, di Piero Bassetti (Marsilio, 2015), \u201c<a href=\"http:\/\/www.globusetlocus.org\/Pubblicazioni\/Despertemos-Italicos-Manifesto-Para-Un-Futuro-Glocal.kl\" target=\"_blank\" rel=\"noopener\">Despertemos italicos! Manifesto para un futuro glocal<\/a>\u201d (Cyngular, 2015); \u201c<a href=\"http:\/\/www.globusetlocus.org\/Pubblicazioni\/LetS-Wake-Up-Italics.kl\" target=\"_blank\" rel=\"noopener\">Let\u2019s wake up, Italics! Manifesto for a glocal future<\/a>\u201d (Calandra Institute, 2017).[\/vc_column_text]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"50\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"50\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row][vc_row force_equal_height_columns=&#8221;main_row&#8221; dfd_row_config=&#8221;full_width_content&#8221; disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/3&#8243; column_bg_position=&#8221;center center&#8221; column_bg_repeat=&#8221;no-repeat&#8221; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1555427463959{padding-left: 8% !important;background-image: url(https:\/\/rnbtheme.com\/fiftieth\/wp-content\/uploads\/sites\/51\/2019\/04\/img-colum-5-1x.jpg?id=296) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:30|padding_right_tablet:20|padding_left_mobile:20|padding_right_mobile:20&#8243; el_class=&#8221;dfd_col-tablet-12&#8243; offset=&#8221;vc_col-lg-4 vc_col-md-4 vc_col-xs-12&#8243;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"150\" data-normal_resolution=\"1024\" data-normal_size=\"150\" data-tablet_resolution=\"800\" data-tablet_size=\"150\" data-mobile_resolution=\"480\" data-mobile_size=\"150\" style=\"height: 150px;\"><\/div><div id=\"dfd-facts-6a97d049261e9-8746\" class=\"dfd-facts-counter  layout-6  cr-animate-gen dfd-counter with-icon\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"module-icon\"><i class=\"featured-icon 7 dfd-fifty-7\" style=\"font-size:85px; color:#7d7d7d; opacity:1;\" ><\/i><\/div><div class=\"content-wrap\"><div class=\"stat-count\"> <div class=\"facts-number call-on-waypoint \" data-animation=\"count\" data-max=\"27\" style=\"font-family:Lustria; font-weight:400; font-style:normal; font-size: 62px; color: #fb404a !important; line-height: 70px; \">0<\/div> <\/div><div class=\"facts-subtitle subtitle\" style=\"font-family:Lustria; font-weight:400; font-style:normal; font-size: 20px; color: #ffffff !important; line-height: 20px; letter-spacing: 0px; \">Years of experience<\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t$(\"head\").append(\"<style>#dfd-facts-6a97d049261e9-8746 {min-height: 85px;}#dfd-facts-6a97d049261e9-8746.layout-8 .module-icon + .content-wrap {padding-left: 105px;}#dfd-facts-6a97d049261e9-8746.layout-9 .content-wrap {padding-right: 105px;}<\/style>\");\r\n\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"150\" data-normal_resolution=\"1024\" data-normal_size=\"150\" data-tablet_resolution=\"800\" data-tablet_size=\"150\" data-mobile_resolution=\"480\" data-mobile_size=\"150\" style=\"height: 150px;\"><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243; column_bg_position=&#8221;center center&#8221; column_bg_repeat=&#8221;no-repeat&#8221; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1555427471479{padding-left: 8% !important;background-image: url(https:\/\/rnbtheme.com\/fiftieth\/wp-content\/uploads\/sites\/51\/2019\/04\/img-colum-6-1x.jpg?id=307) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:30|padding_right_tablet:0|padding_left_mobile:20|padding_right_mobile:20&#8243; el_class=&#8221;dfd_col-tablet-12&#8243; offset=&#8221;vc_col-lg-4 vc_col-md-4 vc_col-xs-12&#8243;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"150\" data-normal_resolution=\"1024\" data-normal_size=\"150\" data-tablet_resolution=\"800\" data-tablet_size=\"150\" data-mobile_resolution=\"480\" data-mobile_size=\"150\" style=\"height: 150px;\"><\/div><div id=\"dfd-facts-6a97d049266a5-403\" class=\"dfd-facts-counter  layout-6  cr-animate-gen dfd-counter with-icon\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"module-icon\"><i class=\"featured-icon 8 dfd-fifty-8\" style=\"font-size:85px; color:#7d7d7d; opacity:1;\" ><\/i><\/div><div class=\"content-wrap\"><div class=\"stat-count\"> <div class=\"facts-number call-on-waypoint \" data-animation=\"count\" data-max=\"326\" style=\"font-family:Lustria; font-weight:400; font-style:normal; font-size: 62px; color: #fb404a !important; line-height: 70px; \">0<\/div> <\/div><div class=\"facts-subtitle subtitle\" style=\"font-family:Lustria; font-weight:400; font-style:normal; font-size: 20px; color: #ffffff !important; line-height: 20px; letter-spacing: 0px; \">Successful cases held<\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t$(\"head\").append(\"<style>#dfd-facts-6a97d049266a5-403 {min-height: 85px;}#dfd-facts-6a97d049266a5-403.layout-8 .module-icon + .content-wrap {padding-left: 105px;}#dfd-facts-6a97d049266a5-403.layout-9 .content-wrap {padding-right: 105px;}<\/style>\");\r\n\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"150\" data-normal_resolution=\"1024\" data-normal_size=\"150\" data-tablet_resolution=\"800\" data-tablet_size=\"150\" data-mobile_resolution=\"480\" data-mobile_size=\"150\" style=\"height: 150px;\"><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243; column_bg_position=&#8221;center center&#8221; column_bg_repeat=&#8221;no-repeat&#8221; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1555427529997{padding-left: 8% !important;background-image: url(https:\/\/rnbtheme.com\/fiftieth\/wp-content\/uploads\/sites\/51\/2019\/04\/img-colum-7-1x.jpg?id=310) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:30|padding_right_tablet:0|padding_left_mobile:20|padding_right_mobile:20&#8243; el_class=&#8221;dfd_col-tablet-12&#8243; offset=&#8221;vc_col-lg-4 vc_col-md-4 vc_col-xs-12&#8243;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"150\" data-normal_resolution=\"1024\" data-normal_size=\"150\" data-tablet_resolution=\"800\" data-tablet_size=\"150\" data-mobile_resolution=\"480\" data-mobile_size=\"150\" style=\"height: 150px;\"><\/div><div id=\"dfd-facts-6a97d04926a25-3902\" class=\"dfd-facts-counter  layout-6  cr-animate-gen dfd-counter with-icon\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"module-icon\"><i class=\"featured-icon 9 dfd-fifty-9\" style=\"font-size:85px; color:#7d7d7d; opacity:1;\" ><\/i><\/div><div class=\"content-wrap\"><div class=\"stat-count\"> <div class=\"facts-number call-on-waypoint \" data-animation=\"count\" data-max=\"137\" style=\"font-family:Lustria; font-weight:400; font-style:normal; font-size: 62px; color: #fb404a !important; line-height: 70px; \">0<\/div> <\/div><div class=\"facts-subtitle subtitle\" style=\"font-family:Lustria; font-weight:400; font-style:normal; font-size: 20px; color: #ffffff !important; line-height: 20px; letter-spacing: 0px; \">Million dollars saved<\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t$(\"head\").append(\"<style>#dfd-facts-6a97d04926a25-3902 {min-height: 85px;}#dfd-facts-6a97d04926a25-3902.layout-8 .module-icon + .content-wrap {padding-left: 105px;}#dfd-facts-6a97d04926a25-3902.layout-9 .content-wrap {padding-right: 105px;}<\/style>\");\r\n\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"150\" data-normal_resolution=\"1024\" data-normal_size=\"150\" data-tablet_resolution=\"800\" data-tablet_size=\"150\" data-mobile_resolution=\"480\" data-mobile_size=\"150\" style=\"height: 150px;\"><\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_right_desktop:20|padding_left_mobile:20|padding_right_mobile:20&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-center style_02 cr-animate-gen dfd-heading-6a97d04926c4e dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d04926c4e\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><h3 class=\"widget-title dfd-title \" style=\"\">Comitato scientifico<\/h3><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d04926c4e.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}@media (max-width: 799px){.dfd-heading-6a97d04926c4e .dfd-title{font-size: 32px !important;line-height: 32px !important;}}@media (max-width: 799px){.dfd-heading-6a97d04926c4e .dfd-sub-title{letter-spacing: 2px !important;}}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"60\" data-normal_resolution=\"1024\" data-normal_size=\"60\" data-tablet_resolution=\"800\" data-tablet_size=\"60\" data-mobile_resolution=\"480\" data-mobile_size=\"60\" style=\"height: 60px;\"><\/div><div id=\"dfd-carousel-6a97d049270aa\" class=\"dfd-carousel-wrapper\"><div class=\"dfd-carousel-module-wrapper  dfd-carousel-horizontal dfd-arrows_aside_offset dfd-keep-arrows dfd-arrows-style_1 dfd-arrows-enabled cr-animate-gen\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"dfd-carousel\"><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 400 400'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-5-400x400.jpeg\" alt=\"Image\"  width=\"400\" height=\"400\" class=\"team-member-photo \"  \/><div class=\"overlay\" ><\/div><a class=\"image-custom-link image-link\" href=\"https:\/\/www4.ceda.polimi.it\/manifesti\/manifesti\/controller\/ricerche\/RicercaPerDocentiPublic.do?evn_didattica=evento&k_doc=81012&aa=2013&lang=IT&jaf_currentWFID=main\"  target=\"_blank\"><\/a><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Prof. Matteo Bolocan Goldstein<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">Politecnico di Milano<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 400 400'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-6-400x400.jpeg\" alt=\"Image\"  width=\"400\" height=\"400\" class=\"team-member-photo \"  \/><div class=\"overlay\" ><\/div><a class=\"image-custom-link image-link\" href=\"https:\/\/www.iulm.it\/wps\/wcm\/connect\/iulmit\/iulm-it\/docenti\/de-giuseppe-massimo\"  target=\"_blank\"><\/a><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Prof. Massimo De Giuseppe<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">IULM \u2013 International University of Languages and Media<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 400 400'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-7-400x400.jpeg\" alt=\"Image\"  width=\"400\" height=\"400\" class=\"team-member-photo \"  \/><div class=\"overlay\" ><\/div><a class=\"image-custom-link image-link\" href=\"https:\/\/faculty.unibocconi.it\/carlogarbarino\/\"  target=\"_blank\"><\/a><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Prof. Carlo Garbarino<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">Universit\u00e0 Commerciale Luigi Bocconi<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 400 400'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-8-400x400.jpeg\" alt=\"Image\"  width=\"400\" height=\"400\" class=\"team-member-photo \"  \/><div class=\"overlay\" ><\/div><a class=\"image-custom-link image-link\" href=\"https:\/\/www.unimib.it\/elisabetta-marafioti\"  target=\"_blank\"><\/a><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Prof. Elisabetta Marafioti<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">Universit\u00e0 degli Studi di Milano-Bicocca<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 400 400'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-9-400x400.jpeg\" alt=\"Image\"  width=\"400\" height=\"400\" class=\"team-member-photo \"  \/><div class=\"overlay\" ><\/div><a class=\"image-custom-link image-link\" href=\"https:\/\/www.unisr.it\/docenti\/s\/sala-roberta\"  target=\"_blank\"><\/a><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Prof. Roberta Sala<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">Universit\u00e0 Vita-Salute San Raffaele<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div><\/div><a href=\"#\" class=\"dfd-slider-control prev\" title=\"Previous slide\"><i class=\"dfd-added-font-icon-left-open2\"><\/i><\/a><a href=\"#\" class=\"dfd-slider-control next\" title=\"Next slide\"><i class=\"dfd-added-font-icon-right-open2\"><\/i><\/a><\/div>\t\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\"use strict\";\r\n\t\t\t\t\t\tvar $carousel = $('#dfd-carousel-6a97d049270aa').find('.dfd-carousel');\r\n\t\t\t\t\t\t$(document).ready(function() {\r\n\t\t\t\t\t\t\tvar $initialized = ($('body').hasClass('page-template-tmp-side-by-side')) ? $carousel.not('.slick-initialized') : $carousel;\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t$carousel.siblings('.dfd-slider-control.prev').click(function(e) {\r\n\t\t\t\t\t\t\t\te.preventDefault();\r\n\t\t\t\t\t\t\t\t$carousel.eq(0).slick('slickPrev');\r\n\t\t\t\t\t\t\t});\r\n\t\t\t\t\t\t\t$carousel.siblings('.dfd-slider-control.next').click(function(e) {\r\n\t\t\t\t\t\t\t\te.preventDefault();\r\n\t\t\t\t\t\t\t\t$carousel.eq(0).slick('slickNext');\r\n\t\t\t\t\t\t\t});\r\n\t\t\t\t\t\t\t$initialized.slick({arrows: false,dotsClass: 'dfd-slick-dots',slidesToScroll: 1,autoplay: true,autoplaySpeed: 5000,dots: false,infinite: true,slidesToShow: 3,speed: 300,swipe: true,draggable: true,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 1024,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 800,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 480,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},]});\r\n\t\t\t\t\t\t\t$(\"head\").append(\"<style>#dfd-carousel-6a97d049270aa > .dfd-carousel-module-wrapper > .dfd-carousel > .slick-list > .slick-track > .dfd-item-wrap > .cover {padding: 0px;}#dfd-carousel-6a97d049270aa {margin: -0px;}#dfd-carousel-6a97d049270aa .dfd-arrows-enabled .dfd-slider-control {margin-top: -70px;}<\/style>\")\t\t\t\t\t\t});\r\n\t\t\t\t\t})(jQuery);\r\n\t\t\t\t<\/script>\r\n            <\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"130\" data-normal_resolution=\"1024\" data-normal_size=\"100\" data-tablet_resolution=\"800\" data-tablet_size=\"100\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 130px;\"><\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_right_desktop:20|padding_left_mobile:20|padding_right_mobile:20&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-center style_02 cr-animate-gen dfd-heading-6a97d0495333f dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d0495333f\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><h3 class=\"widget-title dfd-title \" style=\"\">Staff<\/h3><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d0495333f.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}@media (max-width: 799px){.dfd-heading-6a97d0495333f .dfd-title{font-size: 32px !important;line-height: 32px !important;}}@media (max-width: 799px){.dfd-heading-6a97d0495333f .dfd-sub-title{letter-spacing: 2px !important;}}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"60\" data-normal_resolution=\"1024\" data-normal_size=\"60\" data-tablet_resolution=\"800\" data-tablet_size=\"60\" data-mobile_resolution=\"480\" data-mobile_size=\"60\" style=\"height: 60px;\"><\/div><div id=\"dfd-carousel-6a97d049537be\" class=\"dfd-carousel-wrapper\"><div class=\"dfd-carousel-module-wrapper  dfd-carousel-horizontal dfd-keep-arrows dfd-arrows- dfd-arrows-enabled cr-animate-gen\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"dfd-carousel\"><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><div class=\"overlay\" ><\/div><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Livia D&#039;Anna<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">Responsabile Relazioni Istituzionali<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><div class=\"widget soc-icons dfd-soc-icons-hover-style-1\"><a href=\"mailto:l.danna@globusetlocus.org\" class=\"soc_icon-mail\" target=\"_blank\"><span class=\"line-top-left soc_icon-mail\"><\/span><span class=\"line-top-center soc_icon-mail\"><\/span><span class=\"line-top-right soc_icon-mail\"><\/span><span class=\"line-bottom-left soc_icon-mail\"><\/span><span class=\"line-bottom-center soc_icon-mail\"><\/span><span class=\"line-bottom-right soc_icon-mail\"><\/span><i class=\"soc_icon-mail\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 400 400'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/pp-400x400.jpg\" alt=\"Image\"  width=\"400\" height=\"400\" class=\"team-member-photo \"  \/><div class=\"overlay\" ><\/div><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Vincenzo Politano<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><div class=\"widget soc-icons dfd-soc-icons-hover-style-1\"><a href=\"mailto:v.politano@globusetlocus.org\" class=\"soc_icon-mail\" target=\"_blank\"><span class=\"line-top-left soc_icon-mail\"><\/span><span class=\"line-top-center soc_icon-mail\"><\/span><span class=\"line-top-right soc_icon-mail\"><\/span><span class=\"line-bottom-left soc_icon-mail\"><\/span><span class=\"line-bottom-center soc_icon-mail\"><\/span><span class=\"line-bottom-right soc_icon-mail\"><\/span><i class=\"soc_icon-mail\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-06  cr-animate-gen\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><div class=\"overlay\" ><\/div><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Simone Bruno<\/div><div class=\"wrap-delimiter\"><div class=\"delimiter\" ><\/div><\/div><\/div><\/div><div class=\"content-wrap\"><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\"use strict\";\r\n\t\t\t\t\t\tvar $carousel = $('#dfd-carousel-6a97d049537be').find('.dfd-carousel');\r\n\t\t\t\t\t\t$(document).ready(function() {\r\n\t\t\t\t\t\t\tvar $initialized = ($('body').hasClass('page-template-tmp-side-by-side')) ? $carousel.not('.slick-initialized') : $carousel;\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t$carousel.siblings('.dfd-slider-control.prev').click(function(e) {\r\n\t\t\t\t\t\t\t\te.preventDefault();\r\n\t\t\t\t\t\t\t\t$carousel.eq(0).slick('slickPrev');\r\n\t\t\t\t\t\t\t});\r\n\t\t\t\t\t\t\t$carousel.siblings('.dfd-slider-control.next').click(function(e) {\r\n\t\t\t\t\t\t\t\te.preventDefault();\r\n\t\t\t\t\t\t\t\t$carousel.eq(0).slick('slickNext');\r\n\t\t\t\t\t\t\t});\r\n\t\t\t\t\t\t\t$initialized.slick({arrows: false,dotsClass: 'dfd-slick-dots',slidesToScroll: 1,autoplay: true,autoplaySpeed: 5000,dots: false,infinite: true,slidesToShow: 3,speed: 300,swipe: true,draggable: true,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 1024,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 800,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 480,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},]});\r\n\t\t\t\t\t\t\t$(\"head\").append(\"<style>#dfd-carousel-6a97d049537be > .dfd-carousel-module-wrapper > .dfd-carousel > .slick-list > .slick-track > .dfd-item-wrap > .cover {padding: 0px;}#dfd-carousel-6a97d049537be {margin: -0px;}<\/style>\")\t\t\t\t\t\t});\r\n\t\t\t\t\t})(jQuery);\r\n\t\t\t\t<\/script>\r\n            <\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"130\" data-normal_resolution=\"1024\" data-normal_size=\"100\" data-tablet_resolution=\"800\" data-tablet_size=\"100\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 130px;\"><\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_right_desktop:20|padding_left_mobile:20|padding_right_mobile:20&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-center style_01 cr-animate-gen dfd-heading-6a97d0495971b dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d0495971b\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><h3 class=\"widget-title dfd-title \" style=\"\">Soci<\/h3><div class=\"widget-sub-title dfd-sub-title subtitle\" style=\"letter-spacing: 0px; \">L'Associazione Globus et Locus nasce per volont\u00e0 della Camera di Commercio di Milano e in intesa con l\u2019Universit\u00e0 Cattolica del Sacro Cuore. Negli anni, si \u00e8 verificato un progressivo ampliamento della compagine sociale, con il coinvolgimento di altri enti funzionali e territoriali.<\/div><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d0495971b.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}@media (max-width: 799px){.dfd-heading-6a97d0495971b .dfd-title{font-size: 32px !important;line-height: 32px !important;}}@media (max-width: 799px){.dfd-heading-6a97d0495971b .dfd-sub-title{letter-spacing: 2px !important;}}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"60\" data-normal_resolution=\"1024\" data-normal_size=\"60\" data-tablet_resolution=\"800\" data-tablet_size=\"60\" data-mobile_resolution=\"480\" data-mobile_size=\"60\" style=\"height: 60px;\"><\/div><div id=\"dfd-carousel-6a97d04959be7\" class=\"dfd-carousel-wrapper\"><div class=\"dfd-carousel-module-wrapper  dfd-carousel-horizontal dfd-arrows_aside_offset dfd-keep-arrows dfd-arrows-style_1 dfd-arrows-enabled cr-animate-gen\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"dfd-carousel\">[vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-13-600x600.jpeg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"http:\/\/www.unicatt.it\/\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Universit\u00e0 Cattolica del Sacro Cuore<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">Socio fondatore<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/camera-di-commercio-milano-monza-brianza-lodi-logo-vector-copia-600x600.png\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"http:\/\/www.milomb.camcom.it\/\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Camera di Commercio di Milano-Monza-Brianza-Lodi<\/div><div class=\"team-member-subtitle subtitle\" style=\"font-size: 12px; line-height: 24px; letter-spacing: 1px; \">Socio fondatore<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-14-600x600.jpeg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"http:\/\/www.unioncamere.gov.it\/\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Unioncamere<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/Unioncamere-copia-600x600.jpg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"https:\/\/www.unioncamerelombardia.it\/?\/home\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Unioncamere Lombardia<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/logo-compagnia-san-paolo-600x600.png\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"https:\/\/www.compagniadisanpaolo.it\/it\/\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Compagnia di San Paolo<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/Logo-Milano-copia-600x600.jpg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"https:\/\/www.comune.milano.it\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Comune di Milano<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/20180523-logo-confcommercio-copia-600x600.jpg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"https:\/\/www.confcommercio.it\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Confcommercio<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/image-15-600x600.jpeg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"https:\/\/www.esriitalia.it\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Esri Italia S.p.A.<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/logoipresesenza-copia-600x600.jpg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"https:\/\/www.ipres.it\/it\/\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">IPRES - Regione Puglia<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1645098058791{padding-right: 40px !important;padding-left: 40px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C.35)&#8221;]<div class=\"dfd-item-wrap\"><div class=\"cover\"><div class=\"dfd-team-member layout-01  cr-animate-gen dfd-img-lazy-load\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"image-wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 600 600'%2F%3E\" data-src=\"https:\/\/www.globusetlocus.org\/wp-content\/uploads\/2022\/02\/730x400_Lombardia_copertina-copia-600x600.jpg\" alt=\"Image\"  width=\"600\" height=\"600\" class=\"team-member-photo \"  \/><a class=\"image-custom-link image-link\" href=\"https:\/\/www.regione.lombardia.it\/wps\/portal\/istituzionale\/HP\"  target=\"_blank\"><\/a><\/div><div class=\"content-wrap\"><div class=\"title-wrap\"><div class=\"team-member-title feature-title\" style=\"font-size: 20px; line-height: 24px; \">Regione Lombardia<\/div><\/div><div class=\"team-member-description\" style=\"\"><\/div><\/div><\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<\/div><a href=\"#\" class=\"dfd-slider-control prev\" title=\"Previous slide\"><i class=\"dfd-added-font-icon-left-open2\"><\/i><\/a><a href=\"#\" class=\"dfd-slider-control next\" title=\"Next slide\"><i class=\"dfd-added-font-icon-right-open2\"><\/i><\/a><\/div>\t\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\"use strict\";\r\n\t\t\t\t\t\tvar $carousel = $('#dfd-carousel-6a97d04959be7').find('.dfd-carousel');\r\n\t\t\t\t\t\t$(document).ready(function() {\r\n\t\t\t\t\t\t\tvar $initialized = ($('body').hasClass('page-template-tmp-side-by-side')) ? $carousel.not('.slick-initialized') : $carousel;\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t$carousel.siblings('.dfd-slider-control.prev').click(function(e) {\r\n\t\t\t\t\t\t\t\te.preventDefault();\r\n\t\t\t\t\t\t\t\t$carousel.eq(0).slick('slickPrev');\r\n\t\t\t\t\t\t\t});\r\n\t\t\t\t\t\t\t$carousel.siblings('.dfd-slider-control.next').click(function(e) {\r\n\t\t\t\t\t\t\t\te.preventDefault();\r\n\t\t\t\t\t\t\t\t$carousel.eq(0).slick('slickNext');\r\n\t\t\t\t\t\t\t});\r\n\t\t\t\t\t\t\t$initialized.slick({arrows: false,dotsClass: 'dfd-slick-dots',slidesToScroll: 1,autoplay: true,autoplaySpeed: 5000,dots: false,infinite: true,slidesToShow: 5,speed: 300,swipe: true,draggable: true,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 1024,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 800,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\tbreakpoint: 480,\r\n\t\t\t\t\t\t\t\tsettings: {\r\n\t\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\t\tslidesToScroll: 1,\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},]});\r\n\t\t\t\t\t\t\t$(\"head\").append(\"<style>#dfd-carousel-6a97d04959be7 > .dfd-carousel-module-wrapper > .dfd-carousel > .slick-list > .slick-track > .dfd-item-wrap > .cover {padding: 0px;}#dfd-carousel-6a97d04959be7 {margin: -0px;}#dfd-carousel-6a97d04959be7 .dfd-arrows-enabled .dfd-slider-control {margin-top: -70px;}<\/style>\")\t\t\t\t\t\t});\r\n\t\t\t\t\t})(jQuery);\r\n\t\t\t\t<\/script>\r\n            <\/div><div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"130\" data-normal_resolution=\"1024\" data-normal_size=\"100\" data-tablet_resolution=\"800\" data-tablet_size=\"100\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 130px;\"><\/div>[\/vc_column][\/vc_row][vc_row dfd_row_config=&#8221;full_width_content&#8221; el_class=&#8221;display-class&#8221; disable_element=&#8221;yes&#8221;][vc_column dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1555328526942{margin-top: -100px !important;}&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; el_class=&#8221;z-index-class&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_mobile:20|padding_right_mobile:20&#8243;][vc_row_inner dfd_row_responsive_enable=&#8221;dfd-row-responsive-enable&#8221; css=&#8221;.vc_custom_1555318527806{padding-right: 12% !important;padding-left: 12% !important;}&#8221; el_class=&#8221;row-position-class&#8221; responsive_styles=&#8221;padding_left_mobile:0|padding_right_mobile:0&#8243;][vc_column_inner width=&#8221;1\/3&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; offset=&#8221;vc_col-lg-4 vc_col-md-4 vc_col-xs-4&#8243; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_mobile:10&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_02 cr-animate-gen dfd-heading-6a97d049db38d dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d049db38d\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><div class=\"widget-sub-title dfd-sub-title subtitle\" style=\"color: #ffffff !important; \">BOOK AN<\/div><h3 class=\"widget-title dfd-title \" style=\"font-size: 28px; color: #fb404a !important; line-height: 34px; letter-spacing: 0px; \"><a style=\"color: #fb404a;\" href=\"#\">Appointment<\/a><\/h3><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d049db38d.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;colum-position-class&#8221; width=&#8221;1\/3&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1555425115822{padding-right: 139px !important;padding-left: 139px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:100|padding_right_desktop:0|padding_left_tablet:20|padding_right_tablet:10|padding_left_mobile:0|padding_right_mobile:0&#8243; offset=&#8221;vc_col-lg-4 vc_col-md-4 vc_col-xs-4&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_02 cr-animate-gen dfd-heading-6a97d049db700 dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d049db700\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><div class=\"widget-sub-title dfd-sub-title subtitle\" style=\"color: #ffffff !important; \">TRUSTED SOURCE<\/div><h3 class=\"widget-title dfd-title \" style=\"font-size: 28px; color: #fb404a !important; line-height: 34px; letter-spacing: 0px; \"><a style=\"color: #fb404a;\" href=\"#\">Evaluation<\/a><\/h3><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d049db700.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;colum-position-class-2&#8243; width=&#8221;1\/3&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1555425201439{padding-left: 280px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:140|padding_left_tablet:40|padding_left_mobile:0|padding_right_mobile:0&#8243; offset=&#8221;vc_col-lg-4 vc_col-md-4 vc_col-xs-4&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_02 cr-animate-gen dfd-heading-6a97d049dba07 dfd-disable-resposive-headings\" id=\"dfd-heading-6a97d049dba07\" data-animate-type = \"transition.slideUpBigIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><div class=\"widget-sub-title dfd-sub-title subtitle\" style=\"color: #ffffff !important; \">GET A FREE<\/div><h3 class=\"widget-title dfd-title \" style=\"font-size: 28px; color: #ffffff !important; line-height: 34px; letter-spacing: 0px; \"><a style=\"color: #fff;\" href=\"#\">Consultation<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-56\" style=\"position: absolute; margin-left: 15px;\" src=\"https:\/\/rnbtheme.com\/fiftieth\/wp-content\/uploads\/sites\/51\/2019\/04\/str.png\" alt=\"\" width=\"40\" height=\"23\" \/><\/a><\/h3><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97d049dba07.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row bg_check=&#8221;row-background-dark&#8221; dfd_bg_style=&#8221;image&#8221; dfd_bg_image_new=&#8221;1537&#8243; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#000000&#8243; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;50&#8243;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row dfd_bg_style=&#8221;image&#8221; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#ffffff&#8221; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;85&#8243; disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row<\/p>\n","protected":false},"author":2,"featured_media":2065,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-custom.php","meta":{"footnotes":""},"class_list":["post-2069","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About us - Globus et Locus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.globusetlocus.org\/en\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About us - Globus et Locus\" \/>\n<meta property=\"og:description\" content=\"[vc_row bg_check=&#8221;row-background-dark&#8221; dfd_bg_style=&#8221;image&#8221; dfd_bg_image_new=&#8221;1537&#8243; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#000000&#8243; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;50&#8243;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row dfd_bg_style=&#8221;image&#8221; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#ffffff&#8221; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;85&#8243; disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.globusetlocus.org\/en\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Globus et Locus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T10:01:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/\",\"url\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/\",\"name\":\"About us - Globus et Locus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2019-04-05T08:57:26+00:00\",\"dateModified\":\"2026-01-13T10:01:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/about-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.globusetlocus.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.globusetlocus.org\\\/#website\",\"url\":\"https:\\\/\\\/www.globusetlocus.org\\\/\",\"name\":\"Globus et Locus\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.globusetlocus.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About us - Globus et Locus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.globusetlocus.org\/en\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"About us - Globus et Locus","og_description":"[vc_row bg_check=&#8221;row-background-dark&#8221; dfd_bg_style=&#8221;image&#8221; dfd_bg_image_new=&#8221;1537&#8243; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#000000&#8243; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;50&#8243;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row dfd_bg_style=&#8221;image&#8221; dfd_bg_image_repeat=&#8221;no-repeat&#8221; dfd_bg_image_position=&#8221;center center&#8221; dfd_overlay_color=&#8221;#ffffff&#8221; dfd_overlay_pattern=&#8221;transperant&#8221; dfd_overlay_pattern_opacity=&#8221;85&#8243; disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; responsive_styles=&#8221;padding_left_desktop:20|padding_left_tablet:20|padding_left_mobile:20&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row","og_url":"https:\/\/www.globusetlocus.org\/en\/about-us\/","og_site_name":"Globus et Locus","article_modified_time":"2026-01-13T10:01:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.globusetlocus.org\/en\/about-us\/","url":"https:\/\/www.globusetlocus.org\/en\/about-us\/","name":"About us - Globus et Locus","isPartOf":{"@id":"https:\/\/www.globusetlocus.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.globusetlocus.org\/en\/about-us\/#primaryimage"},"image":{"@id":"https:\/\/www.globusetlocus.org\/en\/about-us\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-04-05T08:57:26+00:00","dateModified":"2026-01-13T10:01:57+00:00","breadcrumb":{"@id":"https:\/\/www.globusetlocus.org\/en\/about-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.globusetlocus.org\/en\/about-us\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.globusetlocus.org\/en\/about-us\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.globusetlocus.org\/en\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.globusetlocus.org\/en\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/www.globusetlocus.org\/#website","url":"https:\/\/www.globusetlocus.org\/","name":"Globus et Locus","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.globusetlocus.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/pages\/2069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/comments?post=2069"}],"version-history":[{"count":1,"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/pages\/2069\/revisions"}],"predecessor-version":[{"id":3993,"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/pages\/2069\/revisions\/3993"}],"wp:attachment":[{"href":"https:\/\/www.globusetlocus.org\/en\/wp-json\/wp\/v2\/media?parent=2069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}